{"id":48519,"date":"2018-06-22T10:37:00","date_gmt":"2018-06-22T10:37:00","guid":{"rendered":"https:\/\/escapehunt.com\/uk\/birmingham\/?page_id=27"},"modified":"2026-05-05T14:16:07","modified_gmt":"2026-05-05T14:16:07","slug":"home","status":"publish","type":"page","link":"https:\/\/escapehunt.com\/uk\/canterbury\/","title":{"rendered":"THE ADVENTURE STARTS HERE"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/landing-city.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-48519","page","type-page","status-publish","hentry"],"acf":{"custom_schema_json":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canterbury Escape Room Games &amp; Experiences | Escape Hunt<\/title>\n<meta name=\"description\" content=\"Experience Canterbury&#039;s best escape room adventures. Perfect for family &amp; friends, parties &amp; corporate events! Are you ready to Escape Hunt?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/escapehunt.com\/uk\/canterbury\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canterbury Escape Room Games &amp; Experiences | Escape Hunt\" \/>\n<meta property=\"og:description\" content=\"Experience Canterbury&#039;s best escape room adventures. Perfect for family &amp; friends, parties &amp; corporate events! Are you ready to Escape Hunt?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/escapehunt.com\/uk\/canterbury\/\" \/>\n<meta property=\"og:site_name\" content=\"Canterbury\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T14:16:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/escapehunt.com\/uk\/canterbury\/\",\"url\":\"https:\/\/escapehunt.com\/uk\/canterbury\/\",\"name\":\"Canterbury Escape Room Games & Experiences | Escape Hunt\",\"isPartOf\":{\"@id\":\"https:\/\/escapehunt.com\/uk\/canterbury\/#website\"},\"datePublished\":\"2018-06-22T10:37:00+00:00\",\"dateModified\":\"2026-05-05T14:16:07+00:00\",\"description\":\"Experience Canterbury's best escape room adventures. Perfect for family & friends, parties & corporate events! Are you ready to Escape Hunt?\",\"breadcrumb\":{\"@id\":\"https:\/\/escapehunt.com\/uk\/canterbury\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/escapehunt.com\/uk\/canterbury\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/escapehunt.com\/uk\/canterbury\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/escapehunt.com\/uk\/canterbury\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"THE ADVENTURE STARTS HERE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/escapehunt.com\/uk\/canterbury\/#website\",\"url\":\"https:\/\/escapehunt.com\/uk\/canterbury\/\",\"name\":\"Canterbury\",\"description\":\"Welcome To A World Of Unlimited Excitement - Escape Hunt - Live Escape Rooms site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/escapehunt.com\/uk\/canterbury\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canterbury Escape Room Games & Experiences | Escape Hunt","description":"Experience Canterbury's best escape room adventures. Perfect for family & friends, parties & corporate events! Are you ready to Escape Hunt?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/escapehunt.com\/uk\/canterbury\/","og_locale":"en_GB","og_type":"article","og_title":"Canterbury Escape Room Games & Experiences | Escape Hunt","og_description":"Experience Canterbury's best escape room adventures. Perfect for family & friends, parties & corporate events! Are you ready to Escape Hunt?","og_url":"https:\/\/escapehunt.com\/uk\/canterbury\/","og_site_name":"Canterbury","article_modified_time":"2026-05-05T14:16:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/escapehunt.com\/uk\/canterbury\/","url":"https:\/\/escapehunt.com\/uk\/canterbury\/","name":"Canterbury Escape Room Games & Experiences | Escape Hunt","isPartOf":{"@id":"https:\/\/escapehunt.com\/uk\/canterbury\/#website"},"datePublished":"2018-06-22T10:37:00+00:00","dateModified":"2026-05-05T14:16:07+00:00","description":"Experience Canterbury's best escape room adventures. Perfect for family & friends, parties & corporate events! Are you ready to Escape Hunt?","breadcrumb":{"@id":"https:\/\/escapehunt.com\/uk\/canterbury\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/escapehunt.com\/uk\/canterbury\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/escapehunt.com\/uk\/canterbury\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/escapehunt.com\/uk\/canterbury\/"},{"@type":"ListItem","position":2,"name":"THE ADVENTURE STARTS HERE"}]},{"@type":"WebSite","@id":"https:\/\/escapehunt.com\/uk\/canterbury\/#website","url":"https:\/\/escapehunt.com\/uk\/canterbury\/","name":"Canterbury","description":"Welcome To A World Of Unlimited Excitement - Escape Hunt - Live Escape Rooms site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escapehunt.com\/uk\/canterbury\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"custom_schema_json":"","_links":{"self":[{"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/pages\/48519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/comments?post=48519"}],"version-history":[{"count":6,"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/pages\/48519\/revisions"}],"predecessor-version":[{"id":49193,"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/pages\/48519\/revisions\/49193"}],"wp:attachment":[{"href":"https:\/\/escapehunt.com\/uk\/canterbury\/wp-json\/wp\/v2\/media?parent=48519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}