{"id":44978,"date":"2020-08-29T13:07:43","date_gmt":"2020-08-29T13:07:43","guid":{"rendered":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/?p=44978"},"modified":"2020-08-29T13:12:48","modified_gmt":"2020-08-29T13:12:48","slug":"notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise","status":"publish","type":"post","link":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/blog\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/","title":{"rendered":"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Vous \u00eates en pleine p\u00e9riode de recrutement et vous recherchez la perle rare \u00e0 ajouter \u00e0 votre \u00e9quipe ?\u00a0 Dans cet article nous allons vous dire pourquoi notre activit\u00e9 favorise le recrutement des meilleurs candidats adapt\u00e9s \u00e0 vos structures !<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eb5c2e;\"><b>Qu\u2019est ce que la \u00ab\u00a0gamification\u00a0\u00bb du recrutement ?<\/b><\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Nouvelle tendance \u00e9mergente depuis quelques ann\u00e9es, ce nouveau mode de recrutement permet d\u2019utiliser le jeu comme mani\u00e8re de s\u00e9lectionner vos candidats en les exposant \u00e0 diff\u00e9rents challenges \u00e0 r\u00e9soudre et \u00e0 des r\u00e8gles qu\u2019il leur faudra respecter.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lors d\u2019une s\u00e9ance de jeu, vous pourrez observer librement, pendant 60 minutes, vos futurs recrues en train de collaborer, r\u00e9fl\u00e9chir et \u00e9changer ensemble d\u2019une mani\u00e8re qui n\u2019est pas possible lors d\u2019un entretien classique. Cette nouvelle m\u00e9thode de recrutement ne remplace pas la m\u00e9thode dite classique, et doit \u00eatre faite en compl\u00e9ment de cette derni\u00e8re, car elle permet de rep\u00e9rer de nouveaux profils en observant la personnalit\u00e9 et les r\u00e9actions du candidat plut\u00f4t que ses comp\u00e9tences.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">La \u00ab\u00a0gamification\u00a0\u00bb peut \u00eatre utilis\u00e9e dans n\u2019importe quel secteur d\u2019activit\u00e9. Le jeu garde son aspect \u00ab fun \u00bb et divertissant, tout en \u00e9tant utile en apportant des gains \u00e0 votre entreprise, selon vos objectifs.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b><span style=\"color: #eb5c2e;\">En quoi consiste notre activit\u00e9 ?<\/span>\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Est-ce n\u00e9cessaire de rappeler en quoi consiste le jeu ?\u00a0<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">L\u2019\u00e9quipe Escape Hunt Clermont-Ferrand vous accueille dans ses locaux afin de vous aider \u00e0 trouver vos prochaines recrues en les testant avec les diff\u00e9rentes \u00e9nigmes de l\u2019une de nos<br \/>\nquatre salles : <a href=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/games\/panique-a-gergovie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Panique \u00e0 Gergovie<\/a>, <a href=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/games\/cercle-noir-des-catacombes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Le cercle noir des catacombes<\/a>, <a href=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/games\/le-fantome-de-la-cathedrale\/\" target=\"_blank\" rel=\"noopener noreferrer\">Le fant\u00f4me de la cath\u00e9drale<\/a> et <a href=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/games\/lasile\/\" target=\"_blank\" rel=\"noopener noreferrer\">l&rsquo;Asile<\/a>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #eb5c2e;\"><b>Quels sont les avantages et les gains d\u2019un recrutement \u00ab\u00a0gamifi\u00e9\u00a0\u00bb avec notre activit\u00e9 ?<\/b><\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00ab On peut en savoir plus sur quelqu&rsquo;un en une heure de jeu qu&rsquo;en une ann\u00e9e de conversation. \u00bb Platon<\/span><\/i><\/p>\n<ol>\n<li style=\"font-weight: 400;\"><b>Observer les <\/b><b><i>soft skills<\/i><\/b><b> de vos futurs collaborateurs<\/b><span style=\"font-weight: 400;\"> : vous avez pu, gr\u00e2ce \u00e0 l\u2019entretien classique et leur CV, conna\u00eetre leurs <\/span><i><span style=\"font-weight: 400;\">hard skills<\/span><\/i><span style=\"font-weight: 400;\">, c\u2019est-\u00e0-dire leurs comp\u00e9tences techniques n\u00e9cessaires pour le poste \u00e0 pourvoir. Mais qu\u2019en est-il de leur caract\u00e8re \u00e9motionnel ou relationnel ? La confiance en soi, le respect des r\u00e8gles, le sens du collectif, l\u2019empathie, la r\u00e9solution des probl\u00e8mes ou bien la capacit\u00e9 \u00e0 demander de l\u2019aide sont des qualit\u00e9s indispensables \u00e0 ma\u00eetriser aujourd\u2019hui dans le monde du travail. En tant qu\u2019observateur pendant le temps du jeu, vous pourrez vous rendre compte de quel(s) candidat(s) poss\u00e8de(nt) les qualit\u00e9s humaines que vous recherchez pour votre \u00e9quipe.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Am\u00e9liorer votre <\/b><b><i>marque employeur<\/i><\/b><span style=\"font-weight: 400;\"> : une bonne image de votre entreprise aupr\u00e8s de vos collaborateurs, employ\u00e9s et futurs candidats, est un \u00e9l\u00e9ment de marketing et de communication essentiel aujourd\u2019hui pour votre structure. Gr\u00e2ce \u00e0 l\u2019utilisation de ce type de recrutement, vous vous d\u00e9marquerez des entreprises concurrentes et favoriserez les meilleurs candidats \u00e0 se tourner vers votre entreprise plut\u00f4t qu\u2019une autre et \u00e0 fid\u00e9liser vos salari\u00e9s. Cette d\u00e9marche permet de valoriser votre entreprise et mettre en \u00e9vidence ses valeurs.\u00a0\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Diminuer le stress du candidat\u00a0<\/b><span style=\"font-weight: 400;\">: le fait que le recruteur ne soit pas pr\u00e9sent dans la salle o\u00f9 le jeu se d\u00e9roule et que le candidat soit plong\u00e9 dans l\u2019ambiance et l\u2019objectif de ce dernier, lui permettra de se d\u00e9voiler plus naturellement et facilement \u00e0 vous sans qu\u2019il en soit conscient. Cette mise en situation vous permettra de ne pas passer \u00e0 c\u00f4t\u00e9 de la perle rare.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Collaborer avec le Game Master\u00a0<\/b><span style=\"font-weight: 400;\">: avant la partie, vous pouvez demander \u00e0 notre \u00e9quipe que certaines instructions qui vous semblent importantes soient mises en \u00e9vidence pendant le briefing ou durant le d\u00e9roulement du jeu. Nous sommes l\u00e0 pour vous aider dans ce processus de recrutement.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Les <\/b><b><i>feedbacks<\/i><\/b><b> d\u2019apr\u00e8s jeu\u00a0<\/b><span style=\"font-weight: 400;\">: apr\u00e8s l\u2019observation \u00e0 travers les cam\u00e9ras et le jeu termin\u00e9, vous pourrez demander des retours aux candidats lors d\u2019un d\u00e9briefing sur leur exp\u00e9rience dans les salles (<\/span><i><span style=\"font-weight: 400;\">Comment vous \u00eates-vous senti\u00a0? Qu\u2019est ce que vous avez pu apprendre sur vous-m\u00eame\u00a0? Quelle erreur ne referiez-vous pas\u00a0? etc\u2026)<\/span><\/i><span style=\"font-weight: 400;\">. Ce moment vous permettra d\u2019observer leur capacit\u00e9 d\u2019analyse et d\u2019auto\u00e9valuation.<br \/>\n<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Nous disposons dans nos locaux d&rsquo;une salle privative en location qui peut \u00eatre mise \u00e0 votre disposition, pour cr\u00e9er une atmosph\u00e8re plus intimiste avec vos candidats, et pour pouvoir vous r\u00e9unir avant et\/ou apr\u00e8s le jeu. <a href=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/packages\/salle-de-reunion\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pour en savoir plus<\/a>. Nous restons \u00e0 votre disposition pour toutes informations compl\u00e9mentaires. \u00c0 vous de jouer !<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates en pleine p\u00e9riode de recrutement et vous recherchez la perle rare \u00e0 ajouter \u00e0 votre \u00e9quipe ?\u00a0 Dans cet article nous allons vous dire pourquoi notre activit\u00e9 favorise&hellip;<\/p>\n","protected":false},"author":78,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,4],"tags":[162,163,164,165,166,167,168,169,170,149,29],"class_list":["post-44978","post","type-post","status-publish","format-standard","hentry","tag-serious-game","tag-recrutement","tag-employeur","tag-collaborateur","tag-joueur","tag-observation","tag-soft-skills","tag-activite","tag-game","tag-jeu","tag-escape-game"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise - Clermont-Ferrand<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise - Clermont-Ferrand\" \/>\n<meta property=\"og:description\" content=\"Vous \u00eates en pleine p\u00e9riode de recrutement et vous recherchez la perle rare \u00e0 ajouter \u00e0 votre \u00e9quipe ?\u00a0 Dans cet article nous allons vous dire pourquoi notre activit\u00e9 favorise&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Clermont-Ferrand\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-29T13:07:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-29T13:12:48+00:00\" \/>\n<meta name=\"author\" content=\"clermontferrand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clermontferrand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\"},\"author\":{\"name\":\"clermontferrand\",\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#\/schema\/person\/4851a26c4f2f99510ce8c91605d9a06a\"},\"headline\":\"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise\",\"datePublished\":\"2020-08-29T13:07:43+00:00\",\"dateModified\":\"2020-08-29T13:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\"},\"wordCount\":780,\"commentCount\":0,\"keywords\":[\"serious game\",\"recrutement\",\"employeur\",\"collaborateur\",\"joueur\",\"observation\",\"soft skills\",\"activit\u00e9\",\"game\",\"jeu\",\"escape game\"],\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\",\"url\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\",\"name\":\"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise - Clermont-Ferrand\",\"isPartOf\":{\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#website\"},\"datePublished\":\"2020-08-29T13:07:43+00:00\",\"dateModified\":\"2020-08-29T13:12:48+00:00\",\"author\":{\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#\/schema\/person\/4851a26c4f2f99510ce8c91605d9a06a\"},\"breadcrumb\":{\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/blog-actualites-bons-plans\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#website\",\"url\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/\",\"name\":\"Clermont-Ferrand\",\"description\":\"Escape Hunt Clermont Ferrand \u2013 Number 1 Escape Game in Clermont Ferrand\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#\/schema\/person\/4851a26c4f2f99510ce8c91605d9a06a\",\"name\":\"clermontferrand\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise - Clermont-Ferrand","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/","og_locale":"fr_FR","og_type":"article","og_title":"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise - Clermont-Ferrand","og_description":"Vous \u00eates en pleine p\u00e9riode de recrutement et vous recherchez la perle rare \u00e0 ajouter \u00e0 votre \u00e9quipe ?\u00a0 Dans cet article nous allons vous dire pourquoi notre activit\u00e9 favorise&hellip;","og_url":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/","og_site_name":"Clermont-Ferrand","article_published_time":"2020-08-29T13:07:43+00:00","article_modified_time":"2020-08-29T13:12:48+00:00","author":"clermontferrand","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"clermontferrand","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/#article","isPartOf":{"@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/"},"author":{"name":"clermontferrand","@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#\/schema\/person\/4851a26c4f2f99510ce8c91605d9a06a"},"headline":"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise","datePublished":"2020-08-29T13:07:43+00:00","dateModified":"2020-08-29T13:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/"},"wordCount":780,"commentCount":0,"keywords":["serious game","recrutement","employeur","collaborateur","joueur","observation","soft skills","activit\u00e9","game","jeu","escape game"],"articleSection":["Blog","Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/","url":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/","name":"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise - Clermont-Ferrand","isPartOf":{"@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#website"},"datePublished":"2020-08-29T13:07:43+00:00","dateModified":"2020-08-29T13:12:48+00:00","author":{"@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#\/schema\/person\/4851a26c4f2f99510ce8c91605d9a06a"},"breadcrumb":{"@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/2020\/08\/29\/notre-activite-comme-nouvel-outil-de-recrutement-pour-votre-entreprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/blog-actualites-bons-plans\/"},{"@type":"ListItem","position":2,"name":"Notre activit\u00e9 comme nouvel outil de recrutement pour votre entreprise"}]},{"@type":"WebSite","@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#website","url":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/","name":"Clermont-Ferrand","description":"Escape Hunt Clermont Ferrand \u2013 Number 1 Escape Game in Clermont Ferrand","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/#\/schema\/person\/4851a26c4f2f99510ce8c91605d9a06a","name":"clermontferrand"}]}},"_links":{"self":[{"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/posts\/44978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/comments?post=44978"}],"version-history":[{"count":4,"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/posts\/44978\/revisions"}],"predecessor-version":[{"id":44983,"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/posts\/44978\/revisions\/44983"}],"wp:attachment":[{"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/media?parent=44978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/categories?post=44978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escapehunt.com\/fr\/clermont-ferrand\/wp-json\/wp\/v2\/tags?post=44978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}